{"id":193,"count":2,"description":"","link":"https:\/\/avnt.co.in\/blog\/tag\/kettles\/","name":"Kettles","slug":"kettles","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kettles Archives - AV&amp;T Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kettles Archives - AV&amp;T Blog\" \/>\n<meta property=\"og:url\" content=\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/\" \/>\n<meta property=\"og:site_name\" content=\"AV&amp;T Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/\",\"url\":\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/\",\"name\":\"Kettles Archives - AV&amp;T Blog\",\"isPartOf\":{\"@id\":\"http:\/\/avnt.co.in\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/avnt.co.in\/blog\/tag\/kettles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/avnt.co.in\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kettles\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/avnt.co.in\/blog\/#website\",\"url\":\"http:\/\/avnt.co.in\/blog\/\",\"name\":\"AV&amp;T Blog\",\"description\":\"AV&amp;T Hospitality Blog\",\"publisher\":{\"@id\":\"http:\/\/avnt.co.in\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/avnt.co.in\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/avnt.co.in\/blog\/#organization\",\"name\":\"AV&T\",\"url\":\"http:\/\/avnt.co.in\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/avnt.co.in\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/avnt.co.in\/blog\/wp-content\/uploads\/2020\/08\/AVT-Solutions-logo-Toll-Free.jpg\",\"contentUrl\":\"https:\/\/avnt.co.in\/blog\/wp-content\/uploads\/2020\/08\/AVT-Solutions-logo-Toll-Free.jpg\",\"width\":1042,\"height\":1042,\"caption\":\"AV&T\"},\"image\":{\"@id\":\"http:\/\/avnt.co.in\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/avnthospitalitysolutions\",\"https:\/\/www.instagram.com\/avnt61403\/\",\"https:\/\/www.linkedin.com\/company\/av-t-hospitality-solutions\/\",\"https:\/\/www.youtube.com\/channel\/UClGHXFSXODRx_1cWiFKoePg?view_as=subscriber\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kettles Archives - AV&amp;T Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/","og_locale":"en_US","og_type":"article","og_title":"Kettles Archives - AV&amp;T Blog","og_url":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/","og_site_name":"AV&amp;T Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/","url":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/","name":"Kettles Archives - AV&amp;T Blog","isPartOf":{"@id":"http:\/\/avnt.co.in\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/avnt.co.in\/blog\/tag\/kettles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/avnt.co.in\/blog\/"},{"@type":"ListItem","position":2,"name":"Kettles"}]},{"@type":"WebSite","@id":"http:\/\/avnt.co.in\/blog\/#website","url":"http:\/\/avnt.co.in\/blog\/","name":"AV&amp;T Blog","description":"AV&amp;T Hospitality Blog","publisher":{"@id":"http:\/\/avnt.co.in\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/avnt.co.in\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/avnt.co.in\/blog\/#organization","name":"AV&T","url":"http:\/\/avnt.co.in\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/avnt.co.in\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/avnt.co.in\/blog\/wp-content\/uploads\/2020\/08\/AVT-Solutions-logo-Toll-Free.jpg","contentUrl":"https:\/\/avnt.co.in\/blog\/wp-content\/uploads\/2020\/08\/AVT-Solutions-logo-Toll-Free.jpg","width":1042,"height":1042,"caption":"AV&T"},"image":{"@id":"http:\/\/avnt.co.in\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avnthospitalitysolutions","https:\/\/www.instagram.com\/avnt61403\/","https:\/\/www.linkedin.com\/company\/av-t-hospitality-solutions\/","https:\/\/www.youtube.com\/channel\/UClGHXFSXODRx_1cWiFKoePg?view_as=subscriber"]}]}},"_links":{"self":[{"href":"https:\/\/avnt.co.in\/blog\/wp-json\/wp\/v2\/tags\/193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avnt.co.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/avnt.co.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/avnt.co.in\/blog\/wp-json\/wp\/v2\/posts?tags=193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}